{"id":17,"count":5,"description":"","link":"https:\/\/ninzio.com\/worksquare\/category\/software\/","name":"Software","slug":"software","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/ninzio.com\/worksquare\/wp-json\/wp\/v2\/categories\/17","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ninzio.com\/worksquare\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/ninzio.com\/worksquare\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/ninzio.com\/worksquare\/wp-json\/wp\/v2\/posts?categories=17"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}